{"id":690,"date":"2010-01-20T20:24:00","date_gmt":"2010-01-20T18:24:00","guid":{"rendered":"https:\/\/home.graf-rasso-gymnasium.de\/home\/zeitzeuge-max-mannheimer-am-grg\/"},"modified":"2014-07-30T13:52:22","modified_gmt":"2014-07-30T11:52:22","slug":"zeitzeuge-max-mannheimer-am-grg","status":"publish","type":"post","link":"https:\/\/home.graf-rasso-gymnasium.de\/home\/2010\/01\/zeitzeuge-max-mannheimer-am-grg\/","title":{"rendered":"Zeitzeuge: Max Mannheimer am GRG"},"content":{"rendered":"<p><img decoding=\"async\" title=\"Image\" src=\"https:\/\/home.graf-rasso-gymnasium.de\/home\/files\/2010\/01\/mamann.jpg\" border=\"0\" alt=\"Image\" \/>&nbsp;<\/p>\n<p>Kurz vor seinem 90. Geburtstag kommt Max Mannheimer am 21.1. 2010 ein weiteres Mal zu einem Vortrag an das Graf-Rasso-Gymnasium. Herr Mannheimer ist \u00dcberlebender der Konzentrationslager Theresienstadt, Auschwitz-Birkenau und Dachau. Max Mannheimer ist seit 1988 Vorsitzender der Lagergemeinschaft Dachau, des Zusammenschlusses der ehemaligen H\u00e4ftlinge des Konzentrationslagers. Seit vielen Jahren ist er mit Vortr\u00e4gen als Zeitzeuge an Schulen und Einrichtungen der Erwachsenenbildung t\u00e4tig. F\u00fcr diese unerm\u00fcdliche Aufkl\u00e4rungsarbeit bis ins hohe Alter wurde er mit zahlreichen Auszeichnungen bedacht, unter anderem mit dem Bundesverdienstkreuz, der Ehrendoktorw\u00fcrde der Ludwig-Maximilians-Universit\u00e4t M\u00fcnchen und der Bayerischen Verfassungsmedaille.<\/p>\n<p>Auch mit dem GRG ist Max Mannheimer seit langem \u00fcber seine Arbeit verbunden und geh\u00f6rte unter anderem auch zu den Ehreng\u00e4sten bei der Einweihung des neuen Schulgeb\u00e4udes zu Beginn des Schuljahrs 2008\/09. Bei seinen Vortr\u00e4gen geht es Herrn Mannheimer nicht um Anklage oder eine vermeintlich noch zu erreichende Gerechtigkeit, sondern vor allem um die authentische Vermittlung seiner Erfahrungen im Konzentrationslager und dar\u00fcber hinaus.<\/p>\n<p>Zuh\u00f6rer am GRG werden die diesj\u00e4hrigen Sch\u00fcler der 9. Jahrgangsstufe sein, die am Vortag mit dem Besuch der Gedenkst\u00e4tte des ehemaligen Konzentrationslagers Dachau eine intensive Auseinandersetzung mit dem Terrorsystem des Nationalsozialismus erfahren haben.<\/p>\n<p>Wer sich f\u00fcr die \u00dcberlebensgeschichte Max Mannheimers interessiert, sollte sich \u201eDER WEISSE RABE&#8220; ansehen, einen Dokumentarfilm von Carolin Otto, der seine erste Kinoauff\u00fchrung am 10.12. 2009 erfuhr. Das Filmteam begleitete Max Mannheimer unter anderem bei einem Besuch in Auschwitz, stellt seine Arbeit als Zeitzeuge vor und zeigt ihn im Gespr\u00e4ch mit Verwandten und Freunden. Derzeit ist der Film in ausgew\u00e4hlten Kinos in M\u00fcnchen und im Umland der Stadt zu sehen. Wo der Film gezeigt wird, kann man unter <a href=\"http:\/\/www.der-weisse-rabe.de\/\">www.der-weisse-rabe.de<\/a> erfahren.<\/p>\n<p>Herr Mannheimer ist seit Ende der f\u00fcnfziger Jahre auch als K\u00fcnstler unter dem Namen ben jakow bekannt geworden. Zuletzt wurden seine Bilder im Rahmen einer Ausstellung in Frankfurt gezeigt. Von der Er\u00f6ffnung der Ausstellung gibt es eine Videodokumentation der Friedrich-Ebert-Stiftung bei YouTube, in der ben jakow \u00fcber die Motivation seiner Malerei spricht und der Betrachter einige seiner Werke kennen lernen kann.<\/p>\n<p>Red: D. Zink<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Kurz vor seinem 90. Geburtstag kommt Max Mannheimer am 21.1. 2010 ein weiteres Mal zu einem Vortrag an das Graf-Rasso-Gymnasium. Herr Mannheimer ist \u00dcberlebender der Konzentrationslager Theresienstadt, Auschwitz-Birkenau und Dachau. Max Mannheimer ist seit 1988 Vorsitzender der Lagergemeinschaft Dachau, des Zusammenschlusses der ehemaligen H\u00e4ftlinge des Konzentrationslagers. Seit vielen Jahren ist er mit Vortr\u00e4gen als [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":689,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,154],"tags":[166,202],"class_list":["post-690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschichte","category-2009-2010","tag-gaeste","tag-geschichte"],"_links":{"self":[{"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/posts\/690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/comments?post=690"}],"version-history":[{"count":1,"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/posts\/690\/revisions"}],"predecessor-version":[{"id":5109,"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/posts\/690\/revisions\/5109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/media\/689"}],"wp:attachment":[{"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/media?parent=690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/categories?post=690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/tags?post=690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}