{"id":877,"date":"2011-01-21T19:19:31","date_gmt":"2011-01-21T17:19:31","guid":{"rendered":"https:\/\/home.graf-rasso-gymnasium.de\/home\/oberstufen-volleyballturnier-2010\/"},"modified":"2014-07-30T13:56:56","modified_gmt":"2014-07-30T11:56:56","slug":"oberstufen-volleyballturnier-2010","status":"publish","type":"post","link":"https:\/\/home.graf-rasso-gymnasium.de\/home\/2011\/01\/oberstufen-volleyballturnier-2010\/","title":{"rendered":"Oberstufen-Volleyballturnier 2010"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/home.graf-rasso-gymnasium.de\/home\/files\/2011\/01\/volleygroup.jpg\" width=\"369\" height=\"246\" align=\"BOTTOM\" border=\"0\" \/><\/p>\n<p>Damit unsere zwei Abiturjahrg\u00e4nge noch ein letztes Mal teilnehmen konnten, fand unser allj\u00e4hrliches Oberstufen-Volleyballturnier bereits in der Woche vor Weihnachten statt.<\/p>\n<p>F\u00fcr die gute Stimmung und den reibungslosen Ablauf m\u00f6chten wir uns bei allen Beteiligten bedanken und den Siegern herzlich gratulieren:<\/p>\n<ul>\n<li>1. Sieger: LK K13 &#8222;Team Hacker&#8220;<\/li>\n<li>2. Sieger: K13 &#8222;Shotgun erster!&#8220;<\/li>\n<li>3. Sieger:Q 11 &#8222;Besser als Nikkis Team&#8220;<\/li>\n<\/ul>\n<p>Euer Organisationsteam<br \/>\nDawid\/Frie\u00df\/Gritsch\/M&#8217;Harzi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Damit unsere zwei Abiturjahrg\u00e4nge noch ein letztes Mal teilnehmen konnten, fand unser allj\u00e4hrliches Oberstufen-Volleyballturnier bereits in der Woche vor Weihnachten statt. F\u00fcr die gute Stimmung und den reibungslosen Ablauf m\u00f6chten wir uns bei allen Beteiligten bedanken und den Siegern herzlich gratulieren: 1. Sieger: LK K13 &#8222;Team Hacker&#8220; 2. Sieger: K13 &#8222;Shotgun erster!&#8220; 3. Sieger:Q 11 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":876,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[155,21],"tags":[206,169],"class_list":["post-877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2010-2011","category-sport","tag-sport","tag-turniere"],"_links":{"self":[{"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/posts\/877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/comments?post=877"}],"version-history":[{"count":2,"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/posts\/877\/revisions"}],"predecessor-version":[{"id":5089,"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/posts\/877\/revisions\/5089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/media\/876"}],"wp:attachment":[{"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/media?parent=877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/categories?post=877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/home.graf-rasso-gymnasium.de\/home\/wp-json\/wp\/v2\/tags?post=877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}